{"id":5813,"date":"2026-07-10T07:22:25","date_gmt":"2026-07-10T05:22:25","guid":{"rendered":"https:\/\/kreuzkirche-addis.de\/home\/?post_type=tribe_events&#038;p=5813"},"modified":"2026-07-10T07:22:25","modified_gmt":"2026-07-10T05:22:25","slug":"16-08-2026-11-uhr-gottesdienst-am-kamin-mit-kirchcafe","status":"publish","type":"tribe_events","link":"https:\/\/kreuzkirche-addis.de\/home\/event\/16-08-2026-11-uhr-gottesdienst-am-kamin-mit-kirchcafe\/","title":{"rendered":"16.08.2026, 11 Uhr: Gottesdienst am Kamin, mit Kirchcaf\u00e9"},"content":{"rendered":"<p>Bis zum 16. August finden in der Regenzeit in Addis Abeba die Gottesdienste in unserer Parish Hall \/ Gemeindesaal statt. Diese Gottesdienste &#8218;light&#8216; in der Ferienzeit haben eine gem\u00fctliche Atmosph\u00e4re und sind einfacher gestaltet. Hier und da kann es aber auch kleine H\u00f6hepunkte geben &#8230;<\/p>\n<p>Herzliche Einladung zum Singen, Beten, auf Gottes Wort h\u00f6ren, zu Gemeinschaft und Begegnung!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bis zum 16. August finden in der Regenzeit in Addis Abeba die Gottesdienste in unserer Parish Hall \/ Gemeindesaal statt. Diese Gottesdienste &#8218;light&#8216; in der Ferienzeit haben eine gem\u00fctliche Atmosph\u00e4re [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5707,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-5813","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","entry","has-media"],"_links":{"self":[{"href":"https:\/\/kreuzkirche-addis.de\/home\/wp-json\/wp\/v2\/tribe_events\/5813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kreuzkirche-addis.de\/home\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/kreuzkirche-addis.de\/home\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/kreuzkirche-addis.de\/home\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/kreuzkirche-addis.de\/home\/wp-json\/wp\/v2\/tribe_events\/5813\/revisions"}],"predecessor-version":[{"id":5814,"href":"https:\/\/kreuzkirche-addis.de\/home\/wp-json\/wp\/v2\/tribe_events\/5813\/revisions\/5814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kreuzkirche-addis.de\/home\/wp-json\/wp\/v2\/media\/5707"}],"wp:attachment":[{"href":"https:\/\/kreuzkirche-addis.de\/home\/wp-json\/wp\/v2\/media?parent=5813"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kreuzkirche-addis.de\/home\/wp-json\/wp\/v2\/tags?post=5813"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/kreuzkirche-addis.de\/home\/wp-json\/wp\/v2\/tribe_events_cat?post=5813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}